{"id":320,"date":"2018-04-30T18:44:23","date_gmt":"2018-04-30T18:44:23","guid":{"rendered":"https:\/\/kineticcuttingsystems.eu\/?page_id=320"},"modified":"2025-11-13T15:00:58","modified_gmt":"2025-11-13T15:00:58","slug":"dreifaches-autogenschneiden","status":"publish","type":"page","link":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/","title":{"rendered":"Dreifaches Autogenschneiden"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">DREIFACHES AUTOGENSCHNEIDEN <\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-331\" src=\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/2018\/05\/triple_oxy_torchw.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg 640w, https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw-300x225.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/h2>\n\n\n\n<p>Das Schneiden mehrerer Schr\u00e4gschnittteile ist jetzt mit dem dreifachen autogenen Brennschneiden-Schr\u00e4gkopf vereinfacht. Komplettes Konturschr\u00e4gschneiden dicker Platten wird mit drei Brennern, die in einem Durchlauf schneiden, erm\u00f6glicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DREIFACHES AUTOGENSCHNEIDEN Das Schneiden mehrerer Schr\u00e4gschnittteile ist jetzt mit dem dreifachen autogenen Brennschneiden-Schr\u00e4gkopf vereinfacht. Komplettes Konturschr\u00e4gschneiden dicker Platten wird mit<a class=\"moretag\" href=\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\"> &#8230;continue reading<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":195,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"page-product.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-320","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme\" \/>\n<meta property=\"og:description\" content=\"DREIFACHES AUTOGENSCHNEIDEN Das Schneiden mehrerer Schr\u00e4gschnittteile ist jetzt mit dem dreifachen autogenen Brennschneiden-Schr\u00e4gkopf vereinfacht. Komplettes Konturschr\u00e4gschneiden dicker Platten wird mit ...continue reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\" \/>\n<meta property=\"og:site_name\" content=\"Kinetic CNC-Metallschneidsysteme\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T15:00:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\",\"url\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\",\"name\":\"Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme\",\"isPartOf\":{\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/2018\/05\/triple_oxy_torchw.jpg\",\"datePublished\":\"2018-04-30T18:44:23+00:00\",\"dateModified\":\"2025-11-13T15:00:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage\",\"url\":\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg\",\"contentUrl\":\"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kineticcuttingsystems.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schneidmaschinen\",\"item\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plasmaoptionen und Zubeh\u00f6r\",\"item\":\"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dreifaches Autogenschneiden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kineticcuttingsystems.eu\/de\/#website\",\"url\":\"https:\/\/kineticcuttingsystems.eu\/de\/\",\"name\":\"Kinetic CNC-Metallschneidsysteme\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kineticcuttingsystems.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/","og_locale":"en_US","og_type":"article","og_title":"Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme","og_description":"DREIFACHES AUTOGENSCHNEIDEN Das Schneiden mehrerer Schr\u00e4gschnittteile ist jetzt mit dem dreifachen autogenen Brennschneiden-Schr\u00e4gkopf vereinfacht. Komplettes Konturschr\u00e4gschneiden dicker Platten wird mit ...continue reading","og_url":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/","og_site_name":"Kinetic CNC-Metallschneidsysteme","article_modified_time":"2025-11-13T15:00:58+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/","url":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/","name":"Dreifaches Autogenschneiden - Kinetic CNC-Metallschneidsysteme","isPartOf":{"@id":"https:\/\/kineticcuttingsystems.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage"},"image":{"@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage"},"thumbnailUrl":"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/2018\/05\/triple_oxy_torchw.jpg","datePublished":"2018-04-30T18:44:23+00:00","dateModified":"2025-11-13T15:00:58+00:00","breadcrumb":{"@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#primaryimage","url":"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg","contentUrl":"https:\/\/kineticcuttingsystems.eu\/de\/wp-content\/uploads\/sites\/3\/2018\/05\/triple_oxy_torchw.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/dreifaches-autogenschneiden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kineticcuttingsystems.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Schneidmaschinen","item":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/"},{"@type":"ListItem","position":3,"name":"Plasmaoptionen und Zubeh\u00f6r","item":"https:\/\/kineticcuttingsystems.eu\/de\/schneidemaschinen\/plasmaoptionen-und-zubehor\/"},{"@type":"ListItem","position":4,"name":"Dreifaches Autogenschneiden"}]},{"@type":"WebSite","@id":"https:\/\/kineticcuttingsystems.eu\/de\/#website","url":"https:\/\/kineticcuttingsystems.eu\/de\/","name":"Kinetic CNC-Metallschneidsysteme","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kineticcuttingsystems.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/pages\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":2,"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/pages\/320\/revisions"}],"predecessor-version":[{"id":3936,"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/pages\/320\/revisions\/3936"}],"up":[{"embeddable":true,"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/pages\/195"}],"wp:attachment":[{"href":"https:\/\/kineticcuttingsystems.eu\/de\/wp-json\/wp\/v2\/media?parent=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}